{"id":18960,"date":"2022-05-04T09:22:38","date_gmt":"2022-05-04T09:22:38","guid":{"rendered":"https:\/\/blendresorts.com\/%d0%b1%d0%bb%d0%b5%d0%bd%d0%b4-%d0%ba%d0%bb%d0%b0%d0%b1-%d0%b0%d0%ba%d0%b2%d0%b0-%d1%80%d0%b5%d0%b7%d0%be%d1%80%d1%82\/"},"modified":"2025-04-22T16:53:29","modified_gmt":"2025-04-22T16:53:29","slug":"%d0%b1%d0%bb%d0%b5%d0%bd%d0%b4-%d0%ba%d0%bb%d0%b0%d0%b1-%d0%b0%d0%ba%d0%b2%d0%b0-%d1%80%d0%b5%d0%b7%d0%be%d1%80%d1%82","status":"publish","type":"page","link":"https:\/\/blendresorts.com\/ru\/%d0%b1%d0%bb%d0%b5%d0%bd%d0%b4-%d0%ba%d0%bb%d0%b0%d0%b1-%d0%b0%d0%ba%d0%b2%d0%b0-%d1%80%d0%b5%d0%b7%d0%be%d1%80%d1%82\/","title":{"rendered":"\u0411\u043b\u0435\u043d\u0434 \u043a\u043b\u0430\u0431 \u0430\u043a\u0432\u0430 \u0440\u0435\u0437\u043e\u0440\u0442"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"18960\" class=\"elementor elementor-18960 elementor-707\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section data-parallax=\"true\" data-parallax-options=\"{&quot;ease&quot;:[&quot;linear&quot;],&quot;start&quot;:&quot;top top&quot;,&quot;end&quot;:&quot;bottom+=0px top&quot;}\" data-parallax-from=\"{&quot;x&quot;:&quot;px&quot;,&quot;opacity&quot;:1}\" data-parallax-to=\"{&quot;x&quot;:&quot;0px&quot;,&quot;opacity&quot;:0}\" class=\"elementor-section elementor-top-section elementor-element elementor-element-836f47c elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"836f47c\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d6a77ad\" data-id=\"d6a77ad\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1e30678 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"1e30678\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e5d16b1\" data-id=\"e5d16b1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-003cb1f elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"003cb1f\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div id=\"ld-fancy-heading-6a97b944c1578\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<h2 class=\"ld-fh-element d-inline-block pos-rel  elementor-heading-title lqd-highlight-classic lqd-highlight-grow-left h2\"  > \u0411\u043b\u0435\u043d\u0434 \u041a\u043b\u0430\u0431<br>\u0410\u043a\u0432\u0430 \u0420\u0435\u0437\u043e\u0440\u0442<\/h2>\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-422eaa66 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"422eaa66\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-69387538\" data-id=\"69387538\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4819a51 elementor-widget elementor-widget-image\" data-id=\"4819a51\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/03\/BCA-01-01-300x300.png\" class=\"attachment-medium size-medium wp-image-17262\" alt=\"\" srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/03\/BCA-01-01-300x300.png 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/03\/BCA-01-01-1024x1024.png 1024w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/03\/BCA-01-01-150x150.png 150w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/03\/BCA-01-01-320x320.png 320w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/03\/BCA-01-01-760x760.png 760w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/03\/BCA-01-01-600x600.png 600w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/03\/BCA-01-01-100x100.png 100w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/03\/elementor\/thumbs\/BCA-01-01-300x300.png 200w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/03\/BCA-01-01.png 1250w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6321a99e elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"6321a99e\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div id=\"ld-fancy-heading-6a97b944c378b\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<p class=\"ld-fh-element d-inline-block pos-rel  lqd-highlight-classic lqd-highlight-grow-left p\"  > \u0412\u0435\u043b\u0438\u0447\u0435\u0441\u0442\u0432\u0435\u043d\u043d\u043e \u0440\u0430\u0441\u043f\u043e\u043b\u043e\u0436\u0438\u0432\u0448\u0438\u0441\u044c \u0432 \u0441\u043f\u043e\u043a\u043e\u0439\u043d\u043e\u043c \u043c\u0435\u0441\u0442\u0435 \u0441 \u0432\u0438\u0434\u043e\u043c \u043d\u0430 \u0436\u0438\u0432\u043e\u043f\u0438\u0441\u043d\u044b\u0439 \u0440\u0435\u0433\u0438\u043e\u043d \u041a\u0440\u0430\u0441\u043d\u043e\u0433\u043e \u043c\u043e\u0440\u044f, Blend Club Aqua Resort \u043f\u0440\u0438\u0433\u043b\u0430\u0448\u0430\u0435\u0442 \u0432\u0430\u0441 \u0438\u0441\u043f\u044b\u0442\u0430\u0442\u044c \u043d\u0435\u0437\u0430\u0431\u044b\u0432\u0430\u0435\u043c\u044b\u0439 \u043e\u0442\u0434\u044b\u0445. \u041e\u0442 \u0440\u0435\u043b\u0430\u043a\u0441\u0430\u0446\u0438\u0438 \u0434\u043e \u0433\u0438\u043f\u0435\u0440\u0430\u043a\u0442\u0438\u0432\u043d\u043e\u0441\u0442\u0438, Blend Club Aqua Resort \u044f\u0432\u043b\u044f\u0435\u0442\u0441\u044f \u043e\u043f\u0442\u0438\u043c\u0430\u043b\u044c\u043d\u044b\u043c \u0432\u044b\u0431\u043e\u0440\u043e\u043c \u0434\u043b\u044f \u0442\u0435\u0445, \u043a\u0442\u043e \u0438\u0449\u0435\u0442 \u0448\u0438\u0440\u043e\u043a\u0438\u0439 \u0441\u043f\u0435\u043a\u0442\u0440 \u0430\u043a\u0442\u0438\u0432\u043d\u043e\u0441\u0442\u0435\u0439 \u0441 \u043e\u0442\u043b\u0438\u0447\u043d\u044b\u043c \u0441\u043e\u043e\u0442\u043d\u043e\u0448\u0435\u043d\u0438\u0435\u043c \u0446\u0435\u043d\u044b \u0438 \u043a\u0430\u0447\u0435\u0441\u0442\u0432\u0430. \u041d\u0430\u0448\u0438 \u0433\u043e\u0441\u0442\u0438 \u043c\u043e\u0433\u0443\u0442 \u043f\u0440\u043e\u0433\u0443\u043b\u0438\u0432\u0430\u0442\u044c\u0441\u044f \u043c\u0435\u0436\u0434\u0443 \u0434\u0432\u0443\u043c\u044f \u0431\u0430\u0441\u0441\u0435\u0439\u043d\u0430\u043c\u0438, \u0430\u043a\u0432\u0430\u043f\u0430\u0440\u043a\u043e\u043c, \u043e\u0431\u0448\u0438\u0440\u043d\u044b\u043c \u043f\u043b\u044f\u0436\u0435\u043c \u0441 \u043e\u0441\u0442\u0440\u043e\u0432\u043a\u043e\u043c, \u0430 \u0442\u0430\u043a\u0436\u0435 \u043a\u043e\u043c\u043f\u043b\u0435\u043a\u0441\u043e\u043c \u0431\u0430\u0440\u043e\u0432 \u0438 \u0440\u0435\u0441\u0442\u043e\u0440\u0430\u043d\u043e\u0432 \u0441 \u0440\u0430\u0437\u043b\u0438\u0447\u043d\u044b\u043c\u0438 \u0430\u0442\u043c\u043e\u0441\u0444\u0435\u0440\u0430\u043c\u0438, \u043e\u0441\u043e\u0437\u043d\u0430\u0432\u0430\u044f, \u0447\u0442\u043e \u043d\u0430\u0448 \u043a\u0443\u0440\u043e\u0440\u0442 \u043f\u0440\u0435\u0434\u043e\u0441\u0442\u0430\u0432\u043b\u044f\u0435\u0442 \u0432\u0441\u0451, \u0447\u0435\u0433\u043e \u043e\u043d\u0438 \u0436\u0435\u043b\u0430\u044e\u0442.   \n<\/p>\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"lqd-css-sticky-column elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-48b01320\" style=\"--lqd-sticky-offset:30px\" data-id=\"48b01320\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2dc56eb5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2dc56eb5\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-35a5789a\" data-id=\"35a5789a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f1d7375 elementor-widget elementor-widget-shortcode\" data-id=\"f1d7375\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><style id=\"sp_lw_dynamic_css10370\">#splw-location-weather-10370.splw-main-wrapper {max-width: 320px;margin : auto;margin-bottom: 2em;}#splw-location-weather-10370.splw-main-wrapper.horizontal {max-width: 800px;}#splw-location-weather-10370 .splw-lite-wrapper,#splw-location-weather-10370 .splw-forecast-weather select,#splw-location-weather-10370 .splw-forecast-weather option,#splw-location-weather-10370 .splw-lite-wrapper .splw-weather-attribution a{text-decoration: none;}#splw-location-weather-10370 .splw-lite-templates-body,#splw-location-weather-10370 .splw-adv-forecast-days{padding : 16px 20px 10px 20px;}#splw-location-weather-10370 .splw-weather-detailed-updated-time{padding : 0 20px 10px 20px;}#splw-location-weather-10370 .splw-lite-wrapper{ border: 0px solid #e2e2e2;}#splw-location-weather-10370 .splw-lite-wrapper .splw-lite-current-temp .splw-weather-icon{width: 58px;}#splw-location-weather-10370 .splw-lite-wrapper{border-radius: 8px;}#splw-location-weather-10370 .splw-lite-daily-weather-details .details-icon i{color:#dfe6e9;}#splw-location-weather-10370 .splw-lite-wrapper,#splw-location-weather-10370 .splw-forecast-weather option{background:#244254}#splw-location-weather-10370 .splw-lite-daily-weather-details.lw-center .splw-other-opt{text-align: center;}#splw-location-weather-10370 .splw-weather-title{color: #000;margin-top: 0px;margin-bottom: 20px;}#splw-location-weather-10370 .splw-lite-header-title{color: #ffffff;margin-top: 0px;margin-bottom: 10px;}#splw-location-weather-10370 .splw-lite-current-time{color: #ffffff;margin-top: 0px;margin-bottom: 10px;}#splw-location-weather-10370 .splw-cur-temp{color: #ffffff;margin-top: 0px;margin-bottom: 0px;}#splw-location-weather-10370 .splw-lite-desc{color: #ffffff;margin-top: 0px;margin-bottom: 0px;}#splw-location-weather-10370 .splw-lite-daily-weather-details{color: #fff;margin-top: 8px;margin-bottom: 8px;}#splw-location-weather-10370 .splw-weather-details .splw-weather-icons {color: #ffffff;margin-top: 20px;margin-bottom: 0px;}#splw-location-weather-10370 .lw-footer{margin-top: 0px;margin-bottom: 0px;}#splw-location-weather-10370 .splw-weather-attribution a,#splw-location-weather-10370 .splw-weather-attribution,#splw-location-weather-10370 .splw-weather-detailed-updated-time a,#splw-location-weather-10370 .splw-weather-updated-time{color: #ffffff;}#splw-location-weather-10370.splw-main-wrapper {position: relative;}#lw-preloader-10370{position: absolute;left: 0;top: 0;height: 100%;width: 100%;text-align: center;display: flex;align-items: center;justify-content: center;background: #fff;z-index: 9999;}<\/style><div id=\"splw-location-weather-10370\" class=\"splw-main-wrapper vertical\" data-shortcode-id=\"10370\">\n\t\t<div id=\"lw-preloader-10370\" class=\"lw-preloader\">\n\t\t\t<img decoding=\"async\" src=\"https:\/\/blendresorts.com\/wp-content\/plugins\/location-weather\/assets\/images\/spinner.svg\" class=\"skip-lazy\"  alt=\"loader-image\" width=\"50\" height=\"50\"\/>\n\t\t<\/div>\n\t\t\t<!-- section title html area start -->\n\t<div class=\"splw-weather-title\">\n\t\tSahl Hashesh\t<\/div>\n<!-- section area end -->\n\t<div class=\"splw-lite-wrapper lw-preloader-wrapper\">\n\t\t<div class=\"splw-lite-templates-body\">\n\t\t\t<div class=\"splw-lite-header\">\n\t<div class=\"splw-lite-header-title-wrapper\">\n\t\t\t\t<div class=\"splw-lite-header-title\">\n\t\t\tHurghada\t\t<\/div>\n\t\t<!-- area end -->\n\t\t<!-- Current Date Time area start -->\n\t\t\t\t\t<div class=\"splw-lite-current-time\">\n\t\t\t\t\t\t\t\t<span class=\"lw-time\">8:51 \u0434\u043f,  <\/span>\n\t\t\t\t<!-- time area end -->\n\t\t\t\t\t\t\t\t<span class=\"lw-date\">2 \u0441\u0435\u043d\u0442\u044f\u0431\u0440\u044f, 2026<\/span>\n\t\t\t\t<!-- date area end -->\n\t\t\t<\/div>\n\t\t<!-- date time area end -->\n\t<\/div>\n<\/div>\n<!-- full area end -->\n<div class=\"splw-lite-current-temp\">\n\t<div class=\"splw-cur-temp\">\n\t\t<!-- weather icon html area start -->\n\t\t<!-- weather icon html area end -->\n\t\t<!-- weather current temperature html area start -->\n\t\t\t\t\t<span class=\"cur-temp\"> \n\t\t\t\t<span class=\"current-temperature\">29<\/span><span class=\"temperature-scale\">\u00b0C<\/span>\t\t\t<\/span>\n\t\t<!-- temperature html area end -->\n\t<\/div>\n<\/div>\n\t<div class=\"splw-lite-desc\">\n\t\tclear sky\t<\/div>\n<div\n\tclass=\"splw-lite-daily-weather-details  lw-center \">\n\t<div class=\"splw-weather-details splw-other-opt\">\n\t\t\t<div class=\"splw-weather-icons icons_splw\">\n\t\t\t\t\t<!-- humidity area start -->\n\t\t\t\t\t\t<div class=\"splw-icon-humidity\">\n\t\t\t\t<span class=\"lw-title-wrapper\">\n\t\t\t\t\t<span class=\"details-icon\" title=\"\u0412\u043b\u0430\u0436\u043d\u043e\u0441\u0442\u044c\"><i class=\"splwp-icon-humidity-1\"><\/i><\/span>\t\t\t\t\t<span class=\"options-title\"><\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class=\"options-value\">\n\t\t\t\t\t42 %\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t<!-- humidity area end -->\n\t\t\t<!-- pressure area start -->\n\t\t\t\t\t\t<div class=\"splw-icon-pressure\">\n\t\t\t\t<span class=\"lw-title-wrapper\">\n\t\t\t\t\t<span class=\"details-icon\" title=\"\u0414\u0430\u0432\u043b\u0435\u043d\u0438\u0435\"><i class=\"splwp-icon-pressure-1\"><\/i><\/span>\t\t\t\t\t<span class=\"options-title\"><\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class=\"options-value\">\n\t\t\t\t\t1009 \u043c\u0431\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t<!-- pressure area end -->\n\t\t\t<!-- wind area start -->\n\t\t\t\t\t\t<div class=\"splw-icon-wind\">\n\t\t\t\t<span class=\"lw-title-wrapper\">\n\t\t\t\t\t<span class=\"details-icon\" title=\"\u0412\u0435\u0442\u0435\u0440\"><i class=\"splwp-icon-wind-1\"><\/i><\/span>\t\t\t\t\t<span class=\"options-title\"><\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class=\"options-value\">\n\t\t\t\t\t19 Km\/h\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t<!-- wind area end -->\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<!-- Wind guest area start -->\n\t\t\t\t<div class=\"splw-gusts-wind\">\n\t\t\t<span class=\"lw-title-wrapper\">\n\t\t\t\t\t\t\t\t<span class=\"options-title\">\u041f\u043e\u0440\u044b\u0432\u044b \u0432\u0435\u0442\u0440\u0430:<\/span>\n\t\t\t<\/span>\n\t\t\t<span class=\"options-value\">\n\t\t\t\t0 Km\/h\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<!-- Wind guest area end -->\n\t\t<!-- Clouds area start -->\n\t\t\t\t<div class=\"splw-clouds\">\n\t\t\t<span class=\"lw-title-wrapper\">\n\t\t\t\t\t\t\t\t<span class=\"options-title\">\u041e\u0431\u043b\u0430\u043a\u0430:<\/span>\n\t\t\t<\/span>\n\t\t\t<span class=\"options-value\">0%<\/span>\n\t\t<\/div>\n\t\t\t\t<!-- Clouds area end -->\n\t\t<!-- Visibility area start -->\n\t\t\t\t<div class=\"splw-visibility\">\n\t\t\t<span class=\"lw-title-wrapper\">\n\t\t\t\t\t\t\t\t<span class=\"options-title\">\u0412\u0438\u0434\u0438\u043c\u043e\u0441\u0442\u044c:<\/span>\n\t\t\t<\/span>\n\t\t\t<span class=\"options-value\">10 \u043a\u043c<\/span>\n\t\t<\/div>\n\t\t\t\t<!-- Visibility area end -->\n\t\t\t\t<div class=\"splw-sunrise\">\n\t\t\t<span class=\"lw-title-wrapper\">\n\t\t\t\t\n\t\t\t\t<span class=\"options-title\">\u0412\u043e\u0441\u0445\u043e\u0434:<\/span>\n\t\t\t<\/span>\n\t\t\t<span class=\"options-value\">6:24 am<\/span>\n\t\t<\/div>\n\t\t<div class=\"splw-sunset\">\n\t\t\t<span class=\"lw-title-wrapper\">\n\t\t\t\t\t\t\t\t<span class=\"options-title\">\u0417\u0430\u043a\u0430\u0442:<\/span>\n\t\t\t<\/span>\n\t\t\t<span class=\"options-value\">7:05 pm<\/span>\n\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\t\t\t<\/div>\n\t\t\t\t<!-- weather detailed and updated html area start -->\n\t<div class=\"lw-footer\">\n\t<!-- weather detailed and updated html area end -->\n<!-- weather attribute html area start -->\n\t\t<div class=\"splw-weather-attribution\">\n\t\t\t\t<a href=\"https:\/\/openweathermap.org\/\" target=\"_blank\">\n\t\t\t\t\t\t\u041f\u043e\u0433\u043e\u0434\u0430 \u043e\u0442 OpenWeatherMap\t\t\t\t<\/a>\n\t\t\t<\/div>\n<!-- weather attribute html area end -->\n<\/div>\n<!-- weather attribute html area end -->\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-59e002f0\" data-id=\"59e002f0\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4004dd9 elementor-align-center elementor-widget elementor-widget-ld_button\" data-id=\"4004dd9\" data-element_type=\"widget\" data-widget_type=\"ld_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<a  href=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/Blend-club-aqua-factsheet2.pdf\" class=\"elementor-button btn align-items-center justify-content-center pos-rel overflow-hidden ws-nowrap btn-solid btn-hover-txt-liquid-y-alt btn-has-label btn-extended-lines\" target=\"_blank\" >\n\t\t\t\t\t\t\t<span class=\"btn-txt d-block pos-rel z-index-3\"  data-text=\"\u0418\u043d\u0444\u043e\u0440\u043c\u0430\u0446\u0438\u043e\u043d\u043d\u044b\u0439 \u043b\u0438\u0441\u0442\" data-split-text=\"true\" data-split-options='{\"type\": \"chars, words\"}'>\n\t\t\t\t\t\t\t\t\t\t\t\u0418\u043d\u0444\u043e\u0440\u043c\u0430\u0446\u0438\u043e\u043d\u043d\u044b\u0439 \u043b\u0438\u0441\u0442\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"btn-extended-line btn-extended-line-tl d-inline-block pos-abs pointer-events-none\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"btn-extended-line btn-extended-line-tr d-inline-block pos-abs pointer-events-none\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"btn-extended-line btn-extended-line-br d-inline-block pos-abs pointer-events-none\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"btn-extended-line btn-extended-line-bl d-inline-block pos-abs pointer-events-none\"><\/i>\n\t\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-543c47e0\" data-id=\"543c47e0\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4d6617fd elementor-shape-circle elementor-grid-0 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"4d6617fd\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-aa2c723\" href=\"https:\/\/www.instagram.com\/blendclubaqua\/?igshid=ZDdkNTZiNTM%3D\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0fddfc7 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"0fddfc7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-66f132e\" data-id=\"66f132e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a8e535f elementor-widget-divider--view-line_text elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"a8e535f\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<h1 class=\"elementor-divider__text elementor-divider__element\">\n\t\t\t\t\u041f\u043e\u043c\u0435\u0449\u0435\u043d\u0438\u044f\t\t\t\t<\/h1>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6da1620 elementor-widget elementor-widget-ld_carousel\" data-id=\"6da1620\" data-element_type=\"widget\" data-widget_type=\"ld_carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"carousel-container pos-rel   carousel-nav-shaped                  \">\n\n\t\t\t<div class=\"carousel-items pos-rel \"  data-lqd-flickity='{\"randomVerOffset\":true,\"marquee\":true,\"marqueeTickerSpeed\":\"0.5\",\"equalHeightCells\":true,\"pauseAutoPlayOnHover\":false}'>\n\n\t\t\t\t\t\t\t\t<div class=\"flickity-viewport pos-rel w-100 overflow-hidden\">\n\t\t\t\t\t<div class=\"flickity-slider d-flex w-100 h-100 pos-rel align-items-start\" style=\"left: 0; transform: translateX(0%);\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/287-1B6A9269-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/287-1B6A9269-1.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/287-1B6A9269-1-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/287-1B6A9269-1-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/286-1B6A9274-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/286-1B6A9274-1.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/286-1B6A9274-1-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/286-1B6A9274-1-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/285-1B6A9724-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/285-1B6A9724-1.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/285-1B6A9724-1-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/285-1B6A9724-1-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/284-1B6A9729-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/284-1B6A9729-1.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/284-1B6A9729-1-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/284-1B6A9729-1-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/283-1B6A9746-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/283-1B6A9746-1.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/283-1B6A9746-1-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/283-1B6A9746-1-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/282-1B6A9751-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/282-1B6A9751-1.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/282-1B6A9751-1-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/282-1B6A9751-1-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/281-1B6A9763-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/281-1B6A9763-1.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/281-1B6A9763-1-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/281-1B6A9763-1-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/279-1B6A9671-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/279-1B6A9671-1.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/279-1B6A9671-1-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/279-1B6A9671-1-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/278-1B6A9656-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/278-1B6A9656-1.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/278-1B6A9656-1-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/278-1B6A9656-1-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/277-1B6A9644-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/277-1B6A9644-1.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/277-1B6A9644-1-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/277-1B6A9644-1-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/276-1B6A9642-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/276-1B6A9642-1.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/276-1B6A9642-1-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/276-1B6A9642-1-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/275-1B6A9696-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/275-1B6A9696-1.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/275-1B6A9696-1-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/275-1B6A9696-1-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/274-1B6A9688-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/274-1B6A9688-1.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/274-1B6A9688-1-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/274-1B6A9688-1-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/273-1B6A9350-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/273-1B6A9350-1.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/273-1B6A9350-1-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/273-1B6A9350-1-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/272-1B6A9460-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/272-1B6A9460-1.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/272-1B6A9460-1-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/272-1B6A9460-1-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/271-1B6A9457-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/271-1B6A9457-1.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/271-1B6A9457-1-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/271-1B6A9457-1-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/270-1B6A9453-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/270-1B6A9453-1.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/270-1B6A9453-1-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/270-1B6A9453-1-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/268-1B6A9392-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/268-1B6A9392-1.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/268-1B6A9392-1-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/268-1B6A9392-1-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/267-1B6A9336-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/267-1B6A9336-1.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/267-1B6A9336-1-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/267-1B6A9336-1-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/266-1B6A9288-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/266-1B6A9288-1.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/266-1B6A9288-1-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/266-1B6A9288-1-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/265-1B6A9635-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/265-1B6A9635-1.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/265-1B6A9635-1-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/265-1B6A9635-1-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/264-1B6A9738-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/264-1B6A9738-1.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/264-1B6A9738-1-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/264-1B6A9738-1-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/263-1B6A9720-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/263-1B6A9720-1.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/263-1B6A9720-1-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/263-1B6A9720-1-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/262-1B6A9713-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/262-1B6A9713-1.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/262-1B6A9713-1-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/262-1B6A9713-1-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/261-1B6A9245-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/261-1B6A9245-1.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/261-1B6A9245-1-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/261-1B6A9245-1-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/260-1B6A9235-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/260-1B6A9235-1.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/260-1B6A9235-1-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/260-1B6A9235-1-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/252-1B6A9229-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/252-1B6A9229-1.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/252-1B6A9229-1-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/252-1B6A9229-1-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/251-1B6A9245-1-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/251-1B6A9245-1-1.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/251-1B6A9245-1-1-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/251-1B6A9245-1-1-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/250-1B6A9235-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/250-1B6A9235-1.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/250-1B6A9235-1-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/250-1B6A9235-1-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14a5191 elementor-widget elementor-widget-spacer\" data-id=\"14a5191\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4707902 elementor-widget-divider--view-line_text elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"4707902\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<h1 class=\"elementor-divider__text elementor-divider__element\">\n\t\t\t\t\u0420\u0435\u0441\u0442\u043e\u0440\u0430\u043d\u044b\t\t\t\t<\/h1>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11e55e5 elementor-widget elementor-widget-ld_carousel\" data-id=\"11e55e5\" data-element_type=\"widget\" data-widget_type=\"ld_carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"carousel-container pos-rel   carousel-nav-shaped                  \">\n\n\t\t\t<div class=\"carousel-items pos-rel \"  data-lqd-flickity='{\"randomVerOffset\":true,\"marquee\":true,\"marqueeTickerSpeed\":\"0.5\",\"equalHeightCells\":true,\"pauseAutoPlayOnHover\":false}'>\n\n\t\t\t\t\t\t\t\t<div class=\"flickity-viewport pos-rel w-100 overflow-hidden\">\n\t\t\t\t\t<div class=\"flickity-slider d-flex w-100 h-100 pos-rel align-items-start\" style=\"left: 0; transform: translateX(0%);\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/292-1B6A0058-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/292-1B6A0058-1.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/292-1B6A0058-1-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/292-1B6A0058-1-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/293-1B6A0060-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/293-1B6A0060-1.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/293-1B6A0060-1-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/293-1B6A0060-1-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/294-1B6A0068-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/294-1B6A0068-1.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/294-1B6A0068-1-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/294-1B6A0068-1-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2267\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2267 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/295-1B6A01954-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/295-1B6A01954-1.jpg 2267w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/295-1B6A01954-1-300x199.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/295-1B6A01954-1-1024x678.jpg 1024w\" data-sizes=\"(max-width: 2267px) 100vw, 2267px\" data-aspect=\"1.5113333333333\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/288-1B6A0042-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/288-1B6A0042-1.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/288-1B6A0042-1-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/288-1B6A0042-1-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2258\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2258 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/289-1B6A0198-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/289-1B6A0198-1.jpg 2258w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/289-1B6A0198-1-300x199.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/289-1B6A0198-1-1024x680.jpg 1024w\" data-sizes=\"(max-width: 2258px) 100vw, 2258px\" data-aspect=\"1.5053333333333\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/290-1B6A0047-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/290-1B6A0047-1.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/290-1B6A0047-1-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/290-1B6A0047-1-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/291-1B6A0055-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/291-1B6A0055-1.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/291-1B6A0055-1-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/291-1B6A0055-1-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2251\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2251 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/253-WhatsApp-Image-2022-09-12-at-12.53.55-PM.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/253-WhatsApp-Image-2022-09-12-at-12.53.55-PM.jpg 2251w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/253-WhatsApp-Image-2022-09-12-at-12.53.55-PM-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/253-WhatsApp-Image-2022-09-12-at-12.53.55-PM-1024x682.jpg 1024w\" data-sizes=\"(max-width: 2251px) 100vw, 2251px\" data-aspect=\"1.5006666666667\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2251\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2251 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/259-WhatsApp-Image-2022-09-12-at-1.00.05-PM.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/259-WhatsApp-Image-2022-09-12-at-1.00.05-PM.jpg 2251w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/259-WhatsApp-Image-2022-09-12-at-1.00.05-PM-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/259-WhatsApp-Image-2022-09-12-at-1.00.05-PM-1024x682.jpg 1024w\" data-sizes=\"(max-width: 2251px) 100vw, 2251px\" data-aspect=\"1.5006666666667\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2251\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2251 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/258-WhatsApp-Image-2022-09-12-at-1.00.05-PM-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/258-WhatsApp-Image-2022-09-12-at-1.00.05-PM-1.jpg 2251w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/258-WhatsApp-Image-2022-09-12-at-1.00.05-PM-1-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/258-WhatsApp-Image-2022-09-12-at-1.00.05-PM-1-1024x682.jpg 1024w\" data-sizes=\"(max-width: 2251px) 100vw, 2251px\" data-aspect=\"1.5006666666667\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2251\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2251 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/257-WhatsApp-Image-2022-09-12-at-1.00.04-PM-2.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/257-WhatsApp-Image-2022-09-12-at-1.00.04-PM-2.jpg 2251w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/257-WhatsApp-Image-2022-09-12-at-1.00.04-PM-2-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/257-WhatsApp-Image-2022-09-12-at-1.00.04-PM-2-1024x682.jpg 1024w\" data-sizes=\"(max-width: 2251px) 100vw, 2251px\" data-aspect=\"1.5006666666667\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2251\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2251 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/256-WhatsApp-Image-2022-09-12-at-1.00.03-PM.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/256-WhatsApp-Image-2022-09-12-at-1.00.03-PM.jpg 2251w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/256-WhatsApp-Image-2022-09-12-at-1.00.03-PM-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/256-WhatsApp-Image-2022-09-12-at-1.00.03-PM-1024x682.jpg 1024w\" data-sizes=\"(max-width: 2251px) 100vw, 2251px\" data-aspect=\"1.5006666666667\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2251\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2251 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/255-WhatsApp-Image-2022-09-12-at-1.00.00-PM.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/255-WhatsApp-Image-2022-09-12-at-1.00.00-PM.jpg 2251w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/255-WhatsApp-Image-2022-09-12-at-1.00.00-PM-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/255-WhatsApp-Image-2022-09-12-at-1.00.00-PM-1024x682.jpg 1024w\" data-sizes=\"(max-width: 2251px) 100vw, 2251px\" data-aspect=\"1.5006666666667\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2251\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2251 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/254-WhatsApp-Image-2022-09-12-at-1.00.00-PM-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/254-WhatsApp-Image-2022-09-12-at-1.00.00-PM-1.jpg 2251w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/254-WhatsApp-Image-2022-09-12-at-1.00.00-PM-1-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/254-WhatsApp-Image-2022-09-12-at-1.00.00-PM-1-1024x682.jpg 1024w\" data-sizes=\"(max-width: 2251px) 100vw, 2251px\" data-aspect=\"1.5006666666667\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14558b7 elementor-widget elementor-widget-spacer\" data-id=\"14558b7\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5b9484 elementor-widget-divider--view-line_text elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"c5b9484\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<h1 class=\"elementor-divider__text elementor-divider__element\">\n\t\t\t\t\u0412\u0435\u0441\u0442\u0438\u0431\u044e\u043b\u044c\t\t\t\t<\/h1>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-80f5379 elementor-widget elementor-widget-ld_carousel\" data-id=\"80f5379\" data-element_type=\"widget\" data-widget_type=\"ld_carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"carousel-container pos-rel   carousel-nav-shaped                  \">\n\n\t\t\t<div class=\"carousel-items pos-rel \"  data-lqd-flickity='{\"randomVerOffset\":true,\"marquee\":true,\"marqueeTickerSpeed\":\"0.5\",\"equalHeightCells\":true,\"pauseAutoPlayOnHover\":false}'>\n\n\t\t\t\t\t\t\t\t<div class=\"flickity-viewport pos-rel w-100 overflow-hidden\">\n\t\t\t\t\t<div class=\"flickity-slider d-flex w-100 h-100 pos-rel align-items-start\" style=\"left: 0; transform: translateX(0%);\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/411-1B6A1450.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/411-1B6A1450.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/411-1B6A1450-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/411-1B6A1450-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"3018\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 3018 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/296-1B6A0094-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/296-1B6A0094-1.jpg 3018w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/296-1B6A0094-1-300x149.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/296-1B6A0094-1-1024x509.jpg 1024w\" data-sizes=\"(max-width: 3018px) 100vw, 3018px\" data-aspect=\"2.012\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/297-1B6A0108-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/297-1B6A0108-1.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/297-1B6A0108-1-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/297-1B6A0108-1-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/298-1B6A0120-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/298-1B6A0120-1.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/298-1B6A0120-1-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/298-1B6A0120-1-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/299-1B6A0123-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/299-1B6A0123-1.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/299-1B6A0123-1-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/299-1B6A0123-1-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/300-1B6A0137-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/300-1B6A0137-1.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/300-1B6A0137-1-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/300-1B6A0137-1-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/301-1B6A0141-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/301-1B6A0141-1.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/301-1B6A0141-1-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/301-1B6A0141-1-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/302-1B6A0144-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/302-1B6A0144-1.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/302-1B6A0144-1-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/302-1B6A0144-1-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/303-1B6A0146-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/303-1B6A0146-1.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/303-1B6A0146-1-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/303-1B6A0146-1-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/304-1B6A0152-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/304-1B6A0152-1.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/304-1B6A0152-1-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/304-1B6A0152-1-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/305-1B6A0158-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/305-1B6A0158-1.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/305-1B6A0158-1-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/305-1B6A0158-1-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/306-1B6A0161-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/306-1B6A0161-1.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/306-1B6A0161-1-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/306-1B6A0161-1-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/407-1B6A1455.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/407-1B6A1455.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/407-1B6A1455-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/407-1B6A1455-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/408-1B6A1457.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/408-1B6A1457.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/408-1B6A1457-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/408-1B6A1457-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/409-1B6A1444.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/409-1B6A1444.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/409-1B6A1444-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/409-1B6A1444-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/410-1B6A1445.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/410-1B6A1445.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/410-1B6A1445-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/410-1B6A1445-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4018e6e elementor-widget elementor-widget-spacer\" data-id=\"4018e6e\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07a7b9f elementor-widget-divider--view-line_text elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"07a7b9f\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<h1 class=\"elementor-divider__text elementor-divider__element\">\n\t\t\t\t\u041f\u043b\u044f\u0436\t\t\t\t<\/h1>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4600378 elementor-widget elementor-widget-ld_carousel\" data-id=\"4600378\" data-element_type=\"widget\" data-widget_type=\"ld_carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"carousel-container pos-rel   carousel-nav-shaped                  \">\n\n\t\t\t<div class=\"carousel-items pos-rel \"  data-lqd-flickity='{\"randomVerOffset\":true,\"marquee\":true,\"marqueeTickerSpeed\":\"0.5\",\"equalHeightCells\":true,\"pauseAutoPlayOnHover\":false}'>\n\n\t\t\t\t\t\t\t\t<div class=\"flickity-viewport pos-rel w-100 overflow-hidden\">\n\t\t\t\t\t<div class=\"flickity-slider d-flex w-100 h-100 pos-rel align-items-start\" style=\"left: 0; transform: translateX(0%);\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2667\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2667 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/445-DJI_0157.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/445-DJI_0157.jpg 2667w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/445-DJI_0157-300x169.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/445-DJI_0157-1024x576.jpg 1024w\" data-sizes=\"(max-width: 2667px) 100vw, 2667px\" data-aspect=\"1.778\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2667\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2667 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/446-DJI_0156.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/446-DJI_0156.jpg 2667w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/446-DJI_0156-300x169.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/446-DJI_0156-1024x576.jpg 1024w\" data-sizes=\"(max-width: 2667px) 100vw, 2667px\" data-aspect=\"1.778\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2667\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2667 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/447-DJI_0155.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/447-DJI_0155.jpg 2667w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/447-DJI_0155-300x169.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/447-DJI_0155-1024x576.jpg 1024w\" data-sizes=\"(max-width: 2667px) 100vw, 2667px\" data-aspect=\"1.778\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2667\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2667 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/448-DJI_0152.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/448-DJI_0152.jpg 2667w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/448-DJI_0152-300x169.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/448-DJI_0152-1024x576.jpg 1024w\" data-sizes=\"(max-width: 2667px) 100vw, 2667px\" data-aspect=\"1.778\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/433-HYPERLAPSE_0021.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/433-HYPERLAPSE_0021.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/433-HYPERLAPSE_0021-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/433-HYPERLAPSE_0021-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/434-HYPERLAPSE_0092.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/434-HYPERLAPSE_0092.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/434-HYPERLAPSE_0092-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/434-HYPERLAPSE_0092-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/435-HYPERLAPSE_0105.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/435-HYPERLAPSE_0105.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/435-HYPERLAPSE_0105-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/435-HYPERLAPSE_0105-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2591\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2591 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/436-HYPERLAPSE_0122.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/436-HYPERLAPSE_0122.jpg 2591w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/436-HYPERLAPSE_0122-300x174.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/436-HYPERLAPSE_0122-1024x593.jpg 1024w\" data-sizes=\"(max-width: 2591px) 100vw, 2591px\" data-aspect=\"1.7273333333333\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/437-HYPERLAPSE_0004.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/437-HYPERLAPSE_0004.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/437-HYPERLAPSE_0004-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/437-HYPERLAPSE_0004-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/438-HYPERLAPSE_0040.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/438-HYPERLAPSE_0040.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/438-HYPERLAPSE_0040-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/438-HYPERLAPSE_0040-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/439-HYPERLAPSE_0067.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/439-HYPERLAPSE_0067.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/439-HYPERLAPSE_0067-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/439-HYPERLAPSE_0067-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/440-HYPERLAPSE_0120.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/440-HYPERLAPSE_0120.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/440-HYPERLAPSE_0120-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/440-HYPERLAPSE_0120-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/441-HYPERLAPSE_0007.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/441-HYPERLAPSE_0007.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/441-HYPERLAPSE_0007-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/441-HYPERLAPSE_0007-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/442-HYPERLAPSE_0023.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/442-HYPERLAPSE_0023.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/442-HYPERLAPSE_0023-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/442-HYPERLAPSE_0023-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/443-HYPERLAPSE_0042.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/443-HYPERLAPSE_0042.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/443-HYPERLAPSE_0042-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/443-HYPERLAPSE_0042-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2667\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2667 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/444-DJI_0162.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/444-DJI_0162.jpg 2667w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/444-DJI_0162-300x169.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/444-DJI_0162-1024x576.jpg 1024w\" data-sizes=\"(max-width: 2667px) 100vw, 2667px\" data-aspect=\"1.778\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/387-1B6A0650.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/387-1B6A0650.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/387-1B6A0650-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/387-1B6A0650-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/386-1B6A0642.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/386-1B6A0642.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/386-1B6A0642-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/386-1B6A0642-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/385-1B6A0618.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/385-1B6A0618.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/385-1B6A0618-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/385-1B6A0618-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/384-1B6A0608.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/384-1B6A0608.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/384-1B6A0608-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/384-1B6A0608-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/383-1B6A0605.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/383-1B6A0605.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/383-1B6A0605-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/383-1B6A0605-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/381-1B6A0571.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/381-1B6A0571.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/381-1B6A0571-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/381-1B6A0571-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/380-1B6A0559.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/380-1B6A0559.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/380-1B6A0559-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/380-1B6A0559-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/378-1B6A0548.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/378-1B6A0548.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/378-1B6A0548-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/378-1B6A0548-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/379-1B6A0558.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/379-1B6A0558.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/379-1B6A0558-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/379-1B6A0558-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3acadee elementor-widget elementor-widget-spacer\" data-id=\"3acadee\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-227ecd5 elementor-widget-divider--view-line_text elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"227ecd5\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<h1 class=\"elementor-divider__text elementor-divider__element\">\n\t\t\t\t\u0411\u0430\u0441\u0441\u0435\u0439\u043d\u044b\t\t\t\t<\/h1>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7bddedb elementor-widget elementor-widget-ld_carousel\" data-id=\"7bddedb\" data-element_type=\"widget\" data-widget_type=\"ld_carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"carousel-container pos-rel   carousel-nav-shaped                  \">\n\n\t\t\t<div class=\"carousel-items pos-rel \"  data-lqd-flickity='{\"randomVerOffset\":true,\"marquee\":true,\"marqueeTickerSpeed\":\"0.5\",\"equalHeightCells\":true,\"pauseAutoPlayOnHover\":false}'>\n\n\t\t\t\t\t\t\t\t<div class=\"flickity-viewport pos-rel w-100 overflow-hidden\">\n\t\t\t\t\t<div class=\"flickity-slider d-flex w-100 h-100 pos-rel align-items-start\" style=\"left: 0; transform: translateX(0%);\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2667\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2667 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/310-DJI_0024-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/310-DJI_0024-1.jpg 2667w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/310-DJI_0024-1-300x169.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/310-DJI_0024-1-1024x576.jpg 1024w\" data-sizes=\"(max-width: 2667px) 100vw, 2667px\" data-aspect=\"1.778\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2667\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2667 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/311-DJI_0026-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/311-DJI_0026-1.jpg 2667w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/311-DJI_0026-1-300x169.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/311-DJI_0026-1-1024x576.jpg 1024w\" data-sizes=\"(max-width: 2667px) 100vw, 2667px\" data-aspect=\"1.778\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"3050\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 3050 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/309-DJI_0023-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/309-DJI_0023-1.jpg 3050w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/309-DJI_0023-1-300x148.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/309-DJI_0023-1-1024x504.jpg 1024w\" data-sizes=\"(max-width: 3050px) 100vw, 3050px\" data-aspect=\"2.0333333333333\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2667\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2667 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/308-DJI_0018-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/308-DJI_0018-1.jpg 2667w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/308-DJI_0018-1-300x169.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/308-DJI_0018-1-1024x576.jpg 1024w\" data-sizes=\"(max-width: 2667px) 100vw, 2667px\" data-aspect=\"1.778\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2667\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2667 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/307-DJI_0017-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/307-DJI_0017-1.jpg 2667w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/307-DJI_0017-1-300x169.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/307-DJI_0017-1-1024x576.jpg 1024w\" data-sizes=\"(max-width: 2667px) 100vw, 2667px\" data-aspect=\"1.778\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/357-1-Relax-Pool.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/357-1-Relax-Pool.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/357-1-Relax-Pool-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/357-1-Relax-Pool-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/356-2-Relax-Pool.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/356-2-Relax-Pool.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/356-2-Relax-Pool-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/356-2-Relax-Pool-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"3111\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 3111 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/354-4-Relax-Pool.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/354-4-Relax-Pool.jpg 3111w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/354-4-Relax-Pool-300x145.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/354-4-Relax-Pool-1024x494.jpg 1024w\" data-sizes=\"(max-width: 3111px) 100vw, 3111px\" data-aspect=\"2.074\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/355-3-Relax-Pool.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/355-3-Relax-Pool.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/355-3-Relax-Pool-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/355-3-Relax-Pool-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2161\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2161 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/353-6-Relax-Pool.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/353-6-Relax-Pool.jpg 2161w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/353-6-Relax-Pool-300x208.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/353-6-Relax-Pool-1024x711.jpg 1024w\" data-sizes=\"(max-width: 2161px) 100vw, 2161px\" data-aspect=\"1.4406666666667\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2895\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2895 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/352-5-Relax-Pool.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/352-5-Relax-Pool.jpg 2895w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/352-5-Relax-Pool-300x155.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/352-5-Relax-Pool-1024x531.jpg 1024w\" data-sizes=\"(max-width: 2895px) 100vw, 2895px\" data-aspect=\"1.93\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/351-7-Relax-Pool.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/351-7-Relax-Pool.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/351-7-Relax-Pool-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/351-7-Relax-Pool-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2704\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2704 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/350-8-Relax-Pool.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/350-8-Relax-Pool.jpg 2704w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/350-8-Relax-Pool-300x166.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/350-8-Relax-Pool-1024x568.jpg 1024w\" data-sizes=\"(max-width: 2704px) 100vw, 2704px\" data-aspect=\"1.8026666666667\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/358-1B6A0449.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/358-1B6A0449.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/358-1B6A0449-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/358-1B6A0449-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2531\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2531 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/359-1B6A0443.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/359-1B6A0443.jpg 2531w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/359-1B6A0443-300x178.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/359-1B6A0443-1024x607.jpg 1024w\" data-sizes=\"(max-width: 2531px) 100vw, 2531px\" data-aspect=\"1.6873333333333\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/360-1B6A0439.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/360-1B6A0439.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/360-1B6A0439-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/360-1B6A0439-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2639\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2639 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/361-1B6A0435.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/361-1B6A0435.jpg 2639w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/361-1B6A0435-300x171.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/361-1B6A0435-1024x582.jpg 1024w\" data-sizes=\"(max-width: 2639px) 100vw, 2639px\" data-aspect=\"1.7593333333333\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1747\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 1747 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/362-1B6A0428.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/362-1B6A0428.jpg 1747w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/362-1B6A0428-300x258.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/362-1B6A0428-1024x879.jpg 1024w\" data-sizes=\"(max-width: 1747px) 100vw, 1747px\" data-aspect=\"1.1646666666667\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/363-1B6A0425.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/363-1B6A0425.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/363-1B6A0425-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/363-1B6A0425-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/364-1B6A0423.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/364-1B6A0423.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/364-1B6A0423-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/364-1B6A0423-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/365-1B6A0420.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/365-1B6A0420.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/365-1B6A0420-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/365-1B6A0420-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/366-1B6A0415.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/366-1B6A0415.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/366-1B6A0415-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/366-1B6A0415-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/367-1B6A0413.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/367-1B6A0413.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/367-1B6A0413-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/367-1B6A0413-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/368-1B6A0411.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/368-1B6A0411.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/368-1B6A0411-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/368-1B6A0411-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2495\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2495 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/369-1B6A0404.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/369-1B6A0404.jpg 2495w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/369-1B6A0404-300x180.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/369-1B6A0404-1024x616.jpg 1024w\" data-sizes=\"(max-width: 2495px) 100vw, 2495px\" data-aspect=\"1.6633333333333\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"3476\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 3476 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/370-1B6A0397.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/370-1B6A0397.jpg 3476w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/370-1B6A0397-300x129.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/370-1B6A0397-1024x442.jpg 1024w\" data-sizes=\"(max-width: 3476px) 100vw, 3476px\" data-aspect=\"2.3173333333333\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2581\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2581 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/371-1B6A0400.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/371-1B6A0400.jpg 2581w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/371-1B6A0400-300x174.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/371-1B6A0400-1024x595.jpg 1024w\" data-sizes=\"(max-width: 2581px) 100vw, 2581px\" data-aspect=\"1.7206666666667\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/372-1B6A0392.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/372-1B6A0392.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/372-1B6A0392-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/372-1B6A0392-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/373-1B6A0385.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/373-1B6A0385.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/373-1B6A0385-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/373-1B6A0385-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2250\" height=\"1500\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 2250 1500&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/374-1B6A0380.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/374-1B6A0380.jpg 2250w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/374-1B6A0380-300x200.jpg 300w, https:\/\/blendresorts.com\/wp-content\/uploads\/2023\/02\/374-1B6A0380-1024x683.jpg 1024w\" data-sizes=\"(max-width: 2250px) 100vw, 2250px\" data-aspect=\"1.5\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7946f84 elementor-widget elementor-widget-spacer\" data-id=\"7946f84\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-42438c4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"42438c4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-abf6668\" data-id=\"abf6668\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cd7faa4 elementor-align-center elementor-widget elementor-widget-ld_counter\" data-id=\"cd7faa4\" data-element_type=\"widget\" data-widget_type=\"ld_counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div id=\"cd7faa4\" class=\"lqd-counter pos-rel center lqd-counter-default\">\n\n\t\t\t\n\t\t\t<div class=\"lqd-counter-element lqd-counter-element-apply-default pos-rel \" data-enable-counter=\"true\" data-counter-options='{\"targetNumber\":\"362\",\"startDelay\":\"500\"}'>\n\t\t\t\t<span class=\"d-block\">362<\/span>\t\t\t<\/div>\n\n\t\t\t<span class=\"lqd-counter-text \">\u041f\u043e\u043c\u0435\u0449\u0435\u043d\u0438\u044f<\/span>\n\n\t\t<\/div>\n\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-51ee5e6\" data-id=\"51ee5e6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef88fae elementor-align-center elementor-widget elementor-widget-ld_counter\" data-id=\"ef88fae\" data-element_type=\"widget\" data-widget_type=\"ld_counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div id=\"ef88fae\" class=\"lqd-counter pos-rel center lqd-counter-default\">\n\n\t\t\t\n\t\t\t<div class=\"lqd-counter-element lqd-counter-element-apply-default pos-rel \" data-enable-counter=\"true\" data-counter-options='{\"targetNumber\":\"2\",\"startDelay\":\"500\"}'>\n\t\t\t\t<span class=\"d-block\">2<\/span>\t\t\t<\/div>\n\n\t\t\t<span class=\"lqd-counter-text \">\u0420\u0435\u0441\u0442\u043e\u0440\u0430\u043d\u044b<\/span>\n\n\t\t<\/div>\n\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-78eb658\" data-id=\"78eb658\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ab517d elementor-align-center elementor-widget elementor-widget-ld_counter\" data-id=\"7ab517d\" data-element_type=\"widget\" data-widget_type=\"ld_counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div id=\"7ab517d\" class=\"lqd-counter pos-rel center lqd-counter-default\">\n\n\t\t\t\n\t\t\t<div class=\"lqd-counter-element lqd-counter-element-apply-default pos-rel \" data-enable-counter=\"true\" data-counter-options='{\"targetNumber\":\"3\",\"startDelay\":\"500\"}'>\n\t\t\t\t<span class=\"d-block\">3<\/span>\t\t\t<\/div>\n\n\t\t\t<span class=\"lqd-counter-text \">\u0411\u0430\u0440\u044b<\/span>\n\n\t\t<\/div>\n\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-a12ad54\" data-id=\"a12ad54\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f6ea4e5 elementor-align-center elementor-widget elementor-widget-ld_counter\" data-id=\"f6ea4e5\" data-element_type=\"widget\" data-widget_type=\"ld_counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div id=\"f6ea4e5\" class=\"lqd-counter pos-rel center lqd-counter-default\">\n\n\t\t\t\n\t\t\t<div class=\"lqd-counter-element lqd-counter-element-apply-default pos-rel \" data-enable-counter=\"true\" data-counter-options='{\"targetNumber\":\"3\",\"startDelay\":\"500\"}'>\n\t\t\t\t<span class=\"d-block\">3<\/span>\t\t\t<\/div>\n\n\t\t\t<span class=\"lqd-counter-text \">\u0411\u0430\u0441\u0441\u0435\u0439\u043d\u044b<\/span>\n\n\t\t<\/div>\n\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dea4114 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"dea4114\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-121d598\" data-id=\"121d598\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ed2213e elementor-widget elementor-widget-ld_google_map\" data-id=\"ed2213e\" data-element_type=\"widget\" data-widget_type=\"ld_google_map.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\t<div class=\"ld-gmap-container pos-rel\">\n\t\t\t\t<div class=\"ld-gmap h-100\" data-plugin-map=\"true\" data-plugin-options='{\"style\":\"evenLighter\",\"address\":\"KM 21 Sahl hasheesh rd, Hurghada, Red Sea Governorate 84511\",\"marker_style\":\"html\",\"markers\":null,\"map\":{\"zoom\":14,\"mapTypeId\":\"roadmap\"}}'><\/div>\n\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-40e1be4 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"40e1be4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0038cf7\" data-id=\"0038cf7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d39f1e5 elementor-widget elementor-widget-ld_carousel\" data-id=\"d39f1e5\" data-element_type=\"widget\" data-widget_type=\"ld_carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"carousel-container pos-rel   carousel-nav-shaped                  \">\n\n\t\t\t<div class=\"carousel-items pos-rel \"  data-lqd-flickity='{\"randomVerOffset\":true,\"marquee\":true,\"marqueeTickerSpeed\":\"0.5\",\"pauseAutoPlayOnHover\":false}'>\n\n\t\t\t\t\t\t\t\t<div class=\"flickity-viewport pos-rel w-100 overflow-hidden\">\n\t\t\t\t\t<div class=\"flickity-slider d-flex w-100 h-100 pos-rel align-items-start\" style=\"left: 0; transform: translateX(0%);\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"698\" height=\"898\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 698 898&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2022\/05\/i8.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2022\/05\/i8.jpg 698w, https:\/\/blendresorts.com\/wp-content\/uploads\/2022\/05\/i8-233x300.jpg 233w\" data-sizes=\"(max-width: 698px) 100vw, 698px\" data-aspect=\"0.77728285077951\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"708\" height=\"914\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 708 914&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2022\/05\/i3.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2022\/05\/i3.jpg 708w, https:\/\/blendresorts.com\/wp-content\/uploads\/2022\/05\/i3-232x300.jpg 232w\" data-sizes=\"(max-width: 708px) 100vw, 708px\" data-aspect=\"0.7746170678337\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"698\" height=\"898\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 698 898&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2022\/05\/i5.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2022\/05\/i5.jpg 698w, https:\/\/blendresorts.com\/wp-content\/uploads\/2022\/05\/i5-233x300.jpg 233w\" data-sizes=\"(max-width: 698px) 100vw, 698px\" data-aspect=\"0.77728285077951\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"698\" height=\"898\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 698 898&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2022\/05\/i6-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2022\/05\/i6-1.jpg 698w, https:\/\/blendresorts.com\/wp-content\/uploads\/2022\/05\/i6-1-233x300.jpg 233w\" data-sizes=\"(max-width: 698px) 100vw, 698px\" data-aspect=\"0.77728285077951\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"728\" height=\"914\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 728 914&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2022\/05\/i2-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2022\/05\/i2-1.jpg 728w, https:\/\/blendresorts.com\/wp-content\/uploads\/2022\/05\/i2-1-239x300.jpg 239w\" data-sizes=\"(max-width: 728px) 100vw, 728px\" data-aspect=\"0.7964989059081\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"698\" height=\"898\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 698 898&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2022\/05\/i7-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2022\/05\/i7-1.jpg 698w, https:\/\/blendresorts.com\/wp-content\/uploads\/2022\/05\/i7-1-233x300.jpg 233w\" data-sizes=\"(max-width: 698px) 100vw, 698px\" data-aspect=\"0.77728285077951\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"730\" height=\"926\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 730 926&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2022\/05\/i1-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2022\/05\/i1-1.jpg 730w, https:\/\/blendresorts.com\/wp-content\/uploads\/2022\/05\/i1-1-237x300.jpg 237w\" data-sizes=\"(max-width: 730px) 100vw, 730px\" data-aspect=\"0.78833693304536\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"632\" height=\"778\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 632 778&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2022\/05\/pf-6.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2022\/05\/pf-6.jpg 632w, https:\/\/blendresorts.com\/wp-content\/uploads\/2022\/05\/pf-6-244x300.jpg 244w\" data-sizes=\"(max-width: 632px) 100vw, 632px\" data-aspect=\"0.81233933161954\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"634\" height=\"768\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 634 768&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2022\/05\/pf-5.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2022\/05\/pf-5.jpg 634w, https:\/\/blendresorts.com\/wp-content\/uploads\/2022\/05\/pf-5-248x300.jpg 248w\" data-sizes=\"(max-width: 634px) 100vw, 634px\" data-aspect=\"0.82552083333333\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"648\" height=\"776\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 648 776&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2022\/05\/pf-4-1.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2022\/05\/pf-4-1.jpg 648w, https:\/\/blendresorts.com\/wp-content\/uploads\/2022\/05\/pf-4-1-251x300.jpg 251w\" data-sizes=\"(max-width: 648px) 100vw, 648px\" data-aspect=\"0.83505154639175\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"622\" height=\"796\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 622 796&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2022\/05\/pf-2.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2022\/05\/pf-2.jpg 622w, https:\/\/blendresorts.com\/wp-content\/uploads\/2022\/05\/pf-2-234x300.jpg 234w\" data-sizes=\"(max-width: 622px) 100vw, 622px\" data-aspect=\"0.78140703517588\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"666\" height=\"812\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 666 812&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2022\/05\/pf-3.jpg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2022\/05\/pf-3.jpg 666w, https:\/\/blendresorts.com\/wp-content\/uploads\/2022\/05\/pf-3-246x300.jpg 246w\" data-sizes=\"(max-width: 666px) 100vw, 666px\" data-aspect=\"0.82019704433498\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"484\" height=\"564\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 484 564&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2022\/05\/fi-2-2-1.jpeg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2022\/05\/fi-2-2-1.jpeg 484w, https:\/\/blendresorts.com\/wp-content\/uploads\/2022\/05\/fi-2-2-1-257x300.jpeg 257w\" data-sizes=\"(max-width: 484px) 100vw, 484px\" data-aspect=\"0.85815602836879\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"432\" height=\"458\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 432 458&#039;%2F%3E\" class=\"attachment-full size-full ld-lazyload\" alt=\"\" data-src=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2022\/05\/fi-1-2-1.jpeg\" data-srcset=\"https:\/\/blendresorts.com\/wp-content\/uploads\/2022\/05\/fi-1-2-1.jpeg 432w, https:\/\/blendresorts.com\/wp-content\/uploads\/2022\/05\/fi-1-2-1-283x300.jpeg 283w\" data-sizes=\"(max-width: 432px) 100vw, 432px\" data-aspect=\"0.94323144104803\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u0411\u043b\u0435\u043d\u0434 \u041a\u043b\u0430\u0431\u0410\u043a\u0432\u0430 \u0420\u0435\u0437\u043e\u0440\u0442 \u0412\u0435\u043b\u0438\u0447\u0435\u0441\u0442\u0432\u0435\u043d\u043d\u043e \u0440\u0430\u0441\u043f\u043e\u043b\u043e\u0436\u0438\u0432\u0448\u0438\u0441\u044c \u0432 \u0441\u043f\u043e\u043a\u043e\u0439\u043d\u043e\u043c \u043c\u0435\u0441\u0442\u0435 \u0441 \u0432\u0438\u0434\u043e\u043c \u043d\u0430 \u0436\u0438\u0432\u043e\u043f\u0438\u0441\u043d\u044b\u0439 \u0440\u0435\u0433\u0438\u043e\u043d \u041a\u0440\u0430\u0441\u043d\u043e\u0433\u043e \u043c\u043e\u0440\u044f, Blend Club Aqua Resort \u043f\u0440\u0438\u0433\u043b\u0430\u0448\u0430\u0435\u0442 \u0432\u0430\u0441 \u0438\u0441\u043f\u044b\u0442\u0430\u0442\u044c \u043d\u0435\u0437\u0430\u0431\u044b\u0432\u0430\u0435\u043c\u044b\u0439 \u043e\u0442\u0434\u044b\u0445. \u041e\u0442 \u0440\u0435\u043b\u0430\u043a\u0441\u0430\u0446\u0438\u0438 \u0434\u043e \u0433\u0438\u043f\u0435\u0440\u0430\u043a\u0442\u0438\u0432\u043d\u043e\u0441\u0442\u0438, Blend Club Aqua Resort \u044f\u0432\u043b\u044f\u0435\u0442\u0441\u044f \u043e\u043f\u0442\u0438\u043c\u0430\u043b\u044c\u043d\u044b\u043c \u0432\u044b\u0431\u043e\u0440\u043e\u043c \u0434\u043b\u044f \u0442\u0435\u0445, \u043a\u0442\u043e \u0438\u0449\u0435\u0442 \u0448\u0438\u0440\u043e\u043a\u0438\u0439 \u0441\u043f\u0435\u043a\u0442\u0440 \u0430\u043a\u0442\u0438\u0432\u043d\u043e\u0441\u0442\u0435\u0439 \u0441 \u043e\u0442\u043b\u0438\u0447\u043d\u044b\u043c \u0441\u043e\u043e\u0442\u043d\u043e\u0448\u0435\u043d\u0438\u0435\u043c \u0446\u0435\u043d\u044b \u0438 \u043a\u0430\u0447\u0435\u0441\u0442\u0432\u0430. \u041d\u0430\u0448\u0438 \u0433\u043e\u0441\u0442\u0438 \u043c\u043e\u0433\u0443\u0442 \u043f\u0440\u043e\u0433\u0443\u043b\u0438\u0432\u0430\u0442\u044c\u0441\u044f \u043c\u0435\u0436\u0434\u0443 \u0434\u0432\u0443\u043c\u044f \u0431\u0430\u0441\u0441\u0435\u0439\u043d\u0430\u043c\u0438, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-18960","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/blendresorts.com\/ru\/wp-json\/wp\/v2\/pages\/18960","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blendresorts.com\/ru\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/blendresorts.com\/ru\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/blendresorts.com\/ru\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blendresorts.com\/ru\/wp-json\/wp\/v2\/comments?post=18960"}],"version-history":[{"count":0,"href":"https:\/\/blendresorts.com\/ru\/wp-json\/wp\/v2\/pages\/18960\/revisions"}],"wp:attachment":[{"href":"https:\/\/blendresorts.com\/ru\/wp-json\/wp\/v2\/media?parent=18960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}